{"id":19367,"date":"2023-01-07T23:29:21","date_gmt":"2023-01-07T22:29:21","guid":{"rendered":"https:\/\/marketinggenerators.com\/?p=19367"},"modified":"2023-01-08T00:30:05","modified_gmt":"2023-01-07T23:30:05","slug":"interne-analyse","status":"publish","type":"post","link":"https:\/\/marketinggenerators.com\/de\/marketing-begriffe\/interne-analyse\/","title":{"rendered":"Interne Analyse"},"content":{"rendered":"\n<p>Eine interne Analyse ist eine Untersuchung der St\u00e4rken und Schw\u00e4chen der Organisation auf der Grundlage eines gr\u00fcndlichen Verst\u00e4ndnisses des Ressourcenprofils der Organisation.&nbsp;Ziel ist es, einen Einblick in die (potenziell) unverwechselbaren Ressourcen der Organisation zu erhalten, die die Grundlage f\u00fcr ihre einzigartigen Wertangebote f\u00fcr Kunden und Wettbewerbsvorteile auf dem Markt bilden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine interne Analyse ist eine Untersuchung der St\u00e4rken und Schw\u00e4chen der Organisation auf der Grundlage eines gr\u00fcndlichen Verst\u00e4ndnisses des Ressourcenprofils der Organisation.&nbsp;Ziel ist es, einen Einblick in die (potenziell) unverwechselbaren Ressourcen der Organisation zu erhalten, die die Grundlage f\u00fcr ihre einzigartigen Wertangebote f\u00fcr Kunden und Wettbewerbsvorteile auf dem Markt bilden.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[899],"tags":[],"class_list":["post-19367","post","type-post","status-publish","format-standard","hentry","category-marketing-begriffe"],"_links":{"self":[{"href":"https:\/\/marketinggenerators.com\/de\/wp-json\/wp\/v2\/posts\/19367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketinggenerators.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marketinggenerators.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marketinggenerators.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marketinggenerators.com\/de\/wp-json\/wp\/v2\/comments?post=19367"}],"version-history":[{"count":0,"href":"https:\/\/marketinggenerators.com\/de\/wp-json\/wp\/v2\/posts\/19367\/revisions"}],"wp:attachment":[{"href":"https:\/\/marketinggenerators.com\/de\/wp-json\/wp\/v2\/media?parent=19367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marketinggenerators.com\/de\/wp-json\/wp\/v2\/categories?post=19367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marketinggenerators.com\/de\/wp-json\/wp\/v2\/tags?post=19367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}